{"id":14,"date":"2022-08-19T17:08:42","date_gmt":"2022-08-19T17:08:42","guid":{"rendered":"https:\/\/dev.wisdomignite.pt\/loja-teste\/?post_type=product&#038;p=14"},"modified":"2022-11-10T15:54:04","modified_gmt":"2022-11-10T15:54:04","slug":"produto-xpto-variavel","status":"publish","type":"product","link":"https:\/\/dev.wisdomignite.pt\/loja-teste\/produto\/produto-xpto-variavel\/","title":{"rendered":"Produto XPTO Variavel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":12,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[15],"product_tag":[],"class_list":["post-14","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-sem-categoria"],"_links":{"self":[{"href":"https:\/\/dev.wisdomignite.pt\/loja-teste\/wp-json\/wp\/v2\/product\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.wisdomignite.pt\/loja-teste\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.wisdomignite.pt\/loja-teste\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/loja-teste\/wp-json\/wp\/v2\/comments?post=14"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/loja-teste\/wp-json\/wp\/v2\/media\/12"}],"wp:attachment":[{"href":"https:\/\/dev.wisdomignite.pt\/loja-teste\/wp-json\/wp\/v2\/media?parent=14"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/loja-teste\/wp-json\/wp\/v2\/product_cat?post=14"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/loja-teste\/wp-json\/wp\/v2\/product_tag?post=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}