{"id":31609,"date":"2022-02-22T15:48:56","date_gmt":"2022-02-22T14:48:56","guid":{"rendered":"https:\/\/dev.wisdomignite.pt\/itv2\/?p=31609"},"modified":"2022-08-25T14:46:20","modified_gmt":"2022-08-25T13:46:20","slug":"internet-of-things","status":"publish","type":"post","link":"https:\/\/dev.wisdomignite.pt\/itv2\/2022\/02\/22\/internet-of-things\/","title":{"rendered":"Internet of Things"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.wisdomignite.pt\/itv2\/wp-content\/uploads\/2022\/05\/iot.jpg\" alt=\"\" class=\"wp-image-31610\" width=\"840\" height=\"558\"\/><\/figure>\n\n\n\n<p>A IoT (Internet of Things), ou em portugu\u00eas \u201cInternet das coisas\u201d, \u00e9 um conceito tecnol\u00f3gico que tem estado em alta nos \u00faltimos anos. A IoT consiste na interconex\u00e3o de qualquer dispositivo eletr\u00f3nico com a Internet, como por exemplo, ve\u00edculos particulares, transportes p\u00fablicos, eletrodom\u00e9sticos, c\u00e2maras de vigil\u00e2ncia, televis\u00f5es, sensores de presen\u00e7a, l\u00e2mpadas, dispositivos m\u00e9dicos, rel\u00f3gios e outros equipamentos.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Atualmente, j\u00e1 \u00e9 poss\u00edvel encontrar dispositivos IoT sendo utilizados tanto em situa\u00e7\u00f5es comuns da vida di\u00e1ria como no \u00e2mbito profissional.<\/p>\n\n\n\n<p>A IoT liga m\u00e1quinas e dispositivos \u00e0 internet, transformando-os em ativos inteligentes que comunicam com o mundo ao seu redor. S\u00e3o equipados com tecnologia que os faz capturar, trocar e enviar informa\u00e7\u00e3o para uma \u00fanica plataforma. Nesta plataforma os dados s\u00e3o analisados e traduzidos em informa\u00e7\u00f5es significativas para a an\u00e1lise do neg\u00f3cio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/dev.wisdomignite.pt\/itv2\/wp-content\/uploads\/2022\/05\/futuristic-smart-city-with-5g-global-network-technology-1024x683.jpg\" alt=\"\" class=\"wp-image-31611\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como funciona?<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>A IoT usa sensores inteligentes, como Bluetooth e GPS, e softwares para recolher e transmitir dados para a rede. Em outras palavras, \u00e9 como uma extens\u00e3o da internet que conecta objetos que fazem parte do dia a dia.<\/p>\n\n\n\n<p>De forma ainda mais resumida, a IoT significa poder controlar certos aparelhos e realizar a\u00e7\u00f5es a partir do seu pr\u00f3prio smartphone ou tablet. De forma ainda mais resumida, a IoT significa poder controlar certos aparelhos e realizar a\u00e7\u00f5es a partir do seu pr\u00f3prio smartphone ou tablet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5g na IoT<\/h2>\n\n\n\n<p>O&nbsp;<strong>5G,&nbsp;<\/strong>\u00e9 a quinta gera\u00e7\u00e3o de rede m\u00f3vel, que promete maior velocidade de download e upload, al\u00e9m de possibilitar conex\u00f5es mais est\u00e1veis e seguras.<\/p>\n\n\n\n<p>A evolu\u00e7\u00e3o mais not\u00e1vel em compara\u00e7\u00e3o com as atuais redes \u00e9 que, al\u00e9m do&nbsp;aumento da velocidade dos dados, os novos casos de uso da IoT e da comunica\u00e7\u00e3o v\u00e3o exigir melhores tipos de&nbsp;desempenho, como a &#8220;baixa lat\u00eancia&#8221;, que fornece uma intera\u00e7\u00e3o em tempo real para os servi\u00e7os que usam a&nbsp;nuvem, o que \u00e9 essencial, por exemplo, para&nbsp;carros conectados, inteligentes e&nbsp;carro aut\u00f3nomo. Al\u00e9m disso, o baixo consumo de energia permitir\u00e1 que objetos conectados funcionem por meses ou anos sem a necessidade de interven\u00e7\u00e3o humana. Para isso, basta estar conectado a uma rede Wi-Fi ou 3G\/4G.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A IoT (Internet of Things), ou em portugu\u00eas \u201cInternet das coisas\u201d, \u00e9 um conceito tecnol\u00f3gico que tem estado em alta nos \u00faltimos anos. A IoT consiste na interconex\u00e3o de qualquer dispositivo eletr\u00f3nico com a Internet, como por exemplo, ve\u00edculos particulares, transportes p\u00fablicos, eletrodom\u00e9sticos, c\u00e2maras de vigil\u00e2ncia, televis\u00f5es, sensores de presen\u00e7a, l\u00e2mpadas, dispositivos m\u00e9dicos, rel\u00f3gios e [&#8230;]\n","protected":false},"author":1,"featured_media":31610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/posts\/31609"}],"collection":[{"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/comments?post=31609"}],"version-history":[{"count":2,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/posts\/31609\/revisions"}],"predecessor-version":[{"id":34106,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/posts\/31609\/revisions\/34106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/media\/31610"}],"wp:attachment":[{"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/media?parent=31609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/categories?post=31609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/tags?post=31609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}