{"id":26973,"date":"2021-03-19T16:39:54","date_gmt":"2021-03-19T15:39:54","guid":{"rendered":"https:\/\/dev.wisdomignite.pt\/itv2\/?p=26973"},"modified":"2022-05-26T16:12:20","modified_gmt":"2022-05-26T15:12:20","slug":"phishing-portugal-e-o-segundo-pais-com-maior-numero-de-ataques","status":"publish","type":"post","link":"https:\/\/dev.wisdomignite.pt\/itv2\/2021\/03\/19\/phishing-portugal-e-o-segundo-pais-com-maior-numero-de-ataques\/","title":{"rendered":"Phishing: Portugal \u00e9 o Segundo Pa\u00eds com maior n\u00famero de ataques"},"content":{"rendered":"\n<p>Anteriormente j\u00e1 abordamos os constrangimentos ligados a ataques de phishing, bem como a forma como este tipo de ataques funcionam.  Segundo dados recentes da Kaspersky n\u00f3s somos o segundo pa\u00eds do mundo que sofreu mais ataques deste g\u00e9nero em compara\u00e7\u00e3o com o Brasil. A <strong><a rel=\"noreferrer noopener\" aria-label=\"wisdom IT CONSULTING (opens in a new tab)\" href=\"https:\/\/www.facebook.com\/wisdomITCONSULTING\" target=\"_blank\">wisdom IT CONSULTING<\/a><\/strong> explica-lhe o porqu\u00ea destas estat\u00edsticas, bem como os procedimentos para <strong><a href=\"https:\/\/dev.wisdomignite.pt\/itv2\/phishing-sabe-o-que-e\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"evitar ser v\u00edtima destes ataques. (opens in a new tab)\">evitar ser v\u00edtima destes ataques.<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Brasil em 1\u00ba lugar, Portugal em 2\u00ba lugar<\/h2>\n\n\n\n<p>S\u00f3 em 2020 foram identificados aproximadamente 430 milh\u00f5es de tentativas de ataques de phishing a n\u00edvel mundial. O Brasil foi o pa\u00eds mais assinalado com estes ataques (19,94%), embora o caso de Portugal n\u00e3o fique muito atr\u00e1s (19,73%). Ainda \u00e9 de salientar o caso da Fran\u00e7a, que este ano chegou ao terceiro lugar com 17,90% de ataques registados, chegando ao top 10 pela primeira vez desde 2015. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/dev.wisdomignite.pt\/itv2\/watchguard\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" loading=\"lazy\" width=\"984\" height=\"791\" src=\"https:\/\/dev.wisdomignite.pt\/itv2\/wp-content\/uploads\/2022\/05\/Phishing-Portugal-e-o-Segundo-Pais-com-maio-numero-de-ataques_4.jpg\" alt=\"Phishing: Portugal \u00e9 o Segundo Pa\u00eds com maior n\u00famero de ataques\" class=\"wp-image-26989\"\/><\/a><figcaption>Fonte: Karspersky<\/figcaption><\/figure>\n\n\n\n<p>Curiosamente, os valores assinalados em 2020 para o Brasil e para Portugal s\u00e3o menos em rela\u00e7\u00e3o a 2019. Apesar de estes dois pa\u00edses terem sido os maiores alvos, no caso do primeiro desceram 10% e no segundo menos 6%.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Este \u00e9 o Top 10 de Pa\u00edses afetados por Phishing <\/h3>\n\n\n\n<ul><li><strong>Brasil: 19,94%<\/strong><\/li><li><strong>Portugal: 19,73%<\/strong><\/li><li><strong>Fran\u00e7a: 17,90%<\/strong><\/li><li><strong>Tun\u00edsia: 17,62%<\/strong><\/li><li><strong>Guiana Francesa: 17,60%<\/strong><\/li><li><strong>Catar: 17,35%<\/strong><\/li><li><strong>Camar\u00f5es: 17,32%<\/strong><\/li><li><strong>Venezuela: 16,84%<\/strong><\/li><li><strong>Nepal: 16,72%<\/strong><\/li><li><strong>Austr\u00e1lia: 16,59%<\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-text-align-center\"><strong>Recomendamos a leitura do nosso artigo sobre Phishing e como funciona. <a href=\"https:\/\/dev.wisdomignite.pt\/itv2\/phishing-sabe-o-que-e\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Para ler o artigo completo clique aqui. (opens in a new tab)\">Para ler o artigo completo clique aqui.<\/a> <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/dev.wisdomignite.pt\/itv2\/panda-security\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"666\" src=\"https:\/\/dev.wisdomignite.pt\/itv2\/wp-content\/uploads\/2022\/05\/Phishing-Portugal-e-o-Segundo-Pais-com-maio-numero-de-ataques_2-1024x666.jpg\" alt=\"Phishing: Portugal \u00e9 o Segundo Pa\u00eds com maior n\u00famero de ataques\" class=\"wp-image-26987\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Porque \u00e9 que se notou um aumento dos ataques?<\/h2>\n\n\n\n<p>Os ataques inform\u00e1ticos em geral foram um dos temas em destaque durante o ano passado. Com efeito, o confinamento e migra\u00e7\u00e3o de muitas pessoas para teletrabalho ter\u00e3o contribu\u00eddo para que se observasse esse mesmo aumento de ataques piratas. <\/p>\n\n\n\n<p>A mesma an\u00e1lise da Karsperky concluiu ainda que uma boa parte do spam (21,27%) teve origem na R\u00fassia tendo sido o email o principal meio usado para os ataques (cerca de 50,37%). Al\u00e9m disso dentro dos tipos de malware usados para esquemas de phishing, destacamos a fam\u00edlia de malware trojan-win32.agentb como o mais utilizado para os ataques. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/dev.wisdomignite.pt\/itv2\/watchguard\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"685\" src=\"https:\/\/dev.wisdomignite.pt\/itv2\/wp-content\/uploads\/2022\/05\/Phishing-Portugal-e-o-Segundo-Pais-com-maio-numero-de-ataques_3-1024x685.jpg\" alt=\"Phishing: Portugal \u00e9 o Segundo Pa\u00eds com maior n\u00famero de ataques\" class=\"wp-image-26988\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Como foram orquestrados os ataques?<\/h2>\n\n\n\n<p>No ano passado os estilos de e-mail mais utilizados pelos hackers envolvia a elabora\u00e7\u00e3o de um e-mail em que se faziam passar por determinadas empresas. Entre os nomes abordados est\u00e3o os da Amazon, PayPal e Microsoft cuja alus\u00e3o pretendia chamar a aten\u00e7\u00e3o dos utilizadores para as contactarem. <\/p>\n\n\n\n<p>Nessas mensagens eram normalmente evocados temas como confirma\u00e7\u00f5es de encomendas, resolu\u00e7\u00e3o de problemas t\u00e9cnicos, cancelamento de transa\u00e7\u00f5es, etc. Em seguida o utilizador era encorajado a ligar a um n\u00famero dispon\u00edvel no e-mail de modo a resolver o problema retratado na mensagem, como alternativa a contactar o suporte t\u00e9cnico dessas empresas.<\/p>\n\n\n\n<p>Al\u00e9m disso, o tema &#8220;COVID-19&#8221; foi bastante usado como um pretexto para divulgar os seus ataques, uma tend\u00eancia que j\u00e1 se viu que ir\u00e1 prevalecer no presente ano. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/dev.wisdomignite.pt\/itv2\/panda-security\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"778\" src=\"https:\/\/dev.wisdomignite.pt\/itv2\/wp-content\/uploads\/2022\/05\/Phishing-Portugal-e-o-Segundo-Pais-com-maio-numero-de-ataques_1-1024x778.jpg\" alt=\"Phishing: Portugal \u00e9 o Segundo Pa\u00eds com maior n\u00famero de ataques\" class=\"wp-image-26986\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Como se precaver de um ataque de phishing<\/h2>\n\n\n\n<ul><li>N\u00e3o abra ficheiros ou anexos suspeitos, especialmente se recebe os mesmos de fontes desconhecidas. <\/li><li>Trate de verificar sempre  o formato do endere\u00e7o das p\u00e1ginas web, bem como a ortografia do nome da empresa. <\/li><li>Evite a instala\u00e7\u00e3o ou download de aplica\u00e7\u00f5es de fontes n\u00e3o vi\u00e1veis. <\/li><li>N\u00e3o clique em links que receba da parte de an\u00fancios suspeitos ou fontes desconhecidas.<\/li><\/ul>\n\n\n\n<h4 class=\"has-text-align-center wp-block-heading\">Descubra ainda as nossas solu\u00e7\u00f5es de seguran\u00e7a TI. Saiba mais sobre a <a href=\"https:\/\/dev.wisdomignite.pt\/itv2\/panda-security\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"PandaSecurity (opens in a new tab)\">PandaSecurity<\/a> e <a href=\"https:\/\/dev.wisdomignite.pt\/itv2\/watchguard\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Watchguard (opens in a new tab)\">Watchguard<\/a>.<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Anteriormente j\u00e1 abordamos os constrangimentos ligados a ataques de phishing, bem como a forma como este tipo de ataques funcionam. Segundo dados recentes da Kaspersky n\u00f3s somos o segundo pa\u00eds do mundo que sofreu mais ataques deste g\u00e9nero em compara\u00e7\u00e3o com o Brasil. A wisdom IT CONSULTING explica-lhe o porqu\u00ea destas estat\u00edsticas, bem como os [&#8230;]\n","protected":false},"author":4,"featured_media":26986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[16,23],"tags":[1621,1624,1626,1628,1627,1625,1622,1623],"_links":{"self":[{"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/posts\/26973"}],"collection":[{"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/comments?post=26973"}],"version-history":[{"count":1,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/posts\/26973\/revisions"}],"predecessor-version":[{"id":34032,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/posts\/26973\/revisions\/34032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/media\/26986"}],"wp:attachment":[{"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/media?parent=26973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/categories?post=26973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/itv2\/wp-json\/wp\/v2\/tags?post=26973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}