{"id":2834,"date":"2022-02-25T16:35:33","date_gmt":"2022-02-25T16:35:33","guid":{"rendered":"https:\/\/dev.wisdomignite.pt\/cea\/?p=2834"},"modified":"2022-02-25T16:35:34","modified_gmt":"2022-02-25T16:35:34","slug":"leguminosas-na-alimentacao","status":"publish","type":"post","link":"https:\/\/dev.wisdomignite.pt\/cea\/leguminosas-na-alimentacao\/","title":{"rendered":"As leguminosas na alimenta\u00e7\u00e3o"},"content":{"rendered":"\n<p>Quem n\u00e3o conhece pratos e petiscos como bacalhau com gr\u00e3o, feij\u00e3o frade com atum e cebolinho, ou uma boa massa de feij\u00e3o vermelho ? O que t\u00eam em comum estas iguarias t\u00e3o t\u00edpicas das mesas portuguesas ? <\/p>\n\n\n\n<p>Certamente todos os nossos leitores j\u00e1 provaram alguns destes sabores e j\u00e1 ter\u00e3o percebido que o que t\u00eam em comum \u00e9 o facto de serem pratos \/ petiscos, em que a sua composi\u00e7\u00e3o \u00e9 rica em leguminosas. <\/p>\n\n\n\n<p>As leguminosas, s\u00e3o sem d\u00favida um tipo de alimento muito presente nas nossas mesas (por vezes bem mais do que parece) e s\u00e3o muito ricas em diversos nutrientes. Genericamente muito ricas em fibras, prote\u00ednas, e bons hidratos de carbono, as leguminosas s\u00e3o muito recomendas em diversos tipos de dietas alimentares.  Esse facto, aliado aos pre\u00e7os convidativos, e \u00e1 facilidade de confe\u00e7\u00e3o, faz com que sejam muito presentes no regime alimentar mediterr\u00e2neo e sem d\u00favida que o sugerimos ter na mesa de sua casa e\/ou da sua empresa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"826\" height=\"551\" src=\"https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2022\/02\/leguminosas.jpg\" alt=\"leguminosas\" class=\"wp-image-2835\" srcset=\"https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2022\/02\/leguminosas.jpg 826w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2022\/02\/leguminosas-510x340.jpg 510w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2022\/02\/leguminosas-300x200.jpg 300w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2022\/02\/leguminosas-768x512.jpg 768w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2022\/02\/leguminosas-370x247.jpg 370w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2022\/02\/leguminosas-770x514.jpg 770w\" sizes=\"(max-width: 826px) 100vw, 826px\" \/><\/figure>\n\n\n\n<h2><strong>Principais leguminosas em Portugal<\/strong><\/h2>\n\n\n\n<p>Em seguida, listamos as principais leguminosas comercializadas em Portugal, assim como as suas principais caracter\u00edsticas.<\/p>\n\n\n\n<h3><strong>Feij\u00e3o vermelho<\/strong><\/h3>\n\n\n\n<p>Ricos em amino\u00e1cidos, antioxidantes, carboidratos, fibras e sais minerais, como c\u00e1lcio, ferro, f\u00f3sforo, magn\u00e9sio, pot\u00e1ssio e zinco, \u00e9 excelente para incluir em massas, arroz, ou sopas.<\/p>\n\n\n\n<h3><strong>Gr\u00e3o de bico<\/strong><\/h3>\n\n\n\n<p>Rico em fibras, prote\u00ednas, vitaminas do complexo B e sais minerais, como c\u00e1lcio, ferro, f\u00f3sforo, magn\u00e9sio e pot\u00e1ssio, \u00e9 um ingrediente que, cru ou cozido, \u00e9 uma \u00f3tima op\u00e7\u00e3o para acompanhar saladas, incluir em sopas, ou at\u00e9 mesmo para fazer pat\u00eas.<\/p>\n\n\n\n<h3><strong>Ervilhas<\/strong><\/h3>\n\n\n\n<p>Com baixo \u00edndice glic\u00eamico, \u00e9 sobretudo composta por fibras, prote\u00ednas, vitaminas e minerais, como c\u00e1lcio. \u00c9 uma op\u00e7\u00e3o muito utilizada para complementar diversos tipos de arroz.<\/p>\n\n\n\n<p>Na Coutinho e Arezes dispomos de uma vasta oferta de leguminosas. Contacte-nos caso pretenda receber um or\u00e7amento personalizado para a sua empresa. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem n\u00e3o conhece pratos e petiscos como bacalhau com gr\u00e3o, feij\u00e3o frade com atum e cebolinho, ou uma boa massa de feij\u00e3o vermelho ? O que t\u00eam em comum estas iguarias t\u00e3o t\u00edpicas das mesas portuguesas ? Certamente todos os nossos leitores j\u00e1 provaram alguns destes sabores e j\u00e1 ter\u00e3o percebido que o que t\u00eam [&#8230;]\n","protected":false},"author":7,"featured_media":2835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[262],"tags":[],"_links":{"self":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/posts\/2834"}],"collection":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/comments?post=2834"}],"version-history":[{"count":2,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/posts\/2834\/revisions"}],"predecessor-version":[{"id":2837,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/posts\/2834\/revisions\/2837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/media\/2835"}],"wp:attachment":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/media?parent=2834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/categories?post=2834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/tags?post=2834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}