{"id":2584,"date":"2021-05-14T11:55:51","date_gmt":"2021-05-14T11:55:51","guid":{"rendered":"https:\/\/dev.wisdomignite.pt\/cea\/?p=2584"},"modified":"2021-06-30T11:17:09","modified_gmt":"2021-06-30T10:17:09","slug":"vitamina-c-qual-a-importancia-das-frutas-citricas","status":"publish","type":"post","link":"https:\/\/dev.wisdomignite.pt\/cea\/vitamina-c-qual-a-importancia-das-frutas-citricas\/","title":{"rendered":"Vitamina C: Qual a import\u00e2ncia das Frutas C\u00edtricas?"},"content":{"rendered":"\n<p>Muitos falam acerca da import\u00e2ncia que as frutas c\u00edtricas t\u00eam para com o sistema imunol\u00f3gico. Nesta categoria podemos incluir frutos como a <strong><a href=\"https:\/\/dev.wisdomignite.pt\/cea\/product-category\/frutas\/laranja\/\" target=\"_blank\" rel=\"noreferrer noopener\">laranja<\/a><\/strong>, a tangerina, o <strong><a href=\"https:\/\/dev.wisdomignite.pt\/cea\/product-category\/frutas\/abacaxi\/\" target=\"_blank\" rel=\"noreferrer noopener\">abacaxi<\/a><\/strong> e o <strong><a href=\"https:\/\/dev.wisdomignite.pt\/cea\/product-category\/frutas\/limao\/\" target=\"_blank\" rel=\"noreferrer noopener\">lim\u00e3o<\/a><\/strong>. Numa era marcada pela COVID-19 que g\u00e9nero de import\u00e2ncia acabam por ter estas frutas? A <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/coutinhoearezes\" target=\"_blank\">Coutinho &amp; Arezes<\/a><\/strong> hoje explica-lhe.<\/p>\n\n\n\n<h2 class=\"has-text-align-center\"><strong>Qual a import\u00e2ncia das Frutas C\u00edtricas para obter Vitamina C?<\/strong><\/h2>\n\n\n\n<p>Mais do que um conjunto de alimentos a incluir na sua dieta, se \u00e9 propenso a gripes e constipa\u00e7\u00f5es, as frutas c\u00edtricas s\u00e3o, acima de tudo um potencial aliado no que toca a prevenir a COVID-19. Isto porque estas frutas s\u00e3o ricas em vitamina C, um componente essencial na forma\u00e7\u00e3o do col\u00e1geno. Por sua vez este trata-se de uma prote\u00edna que d\u00e1 elasticidade e firmeza \u00e0 pele, al\u00e9m de tamb\u00e9m fortalecer o sistema imunol\u00f3gico. Tamb\u00e9m s\u00e3o ricas em \u00e1cido c\u00edtrico, pot\u00e1ssio, vitamina A e flavonoides (importantes para redu\u00e7\u00e3o dos lip\u00eddios).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-2-720x1024.jpg\" alt=\"Vitamina C: Qual a import\u00e2ncia das Frutas C\u00edtricas?\" class=\"wp-image-2587\" width=\"410\" height=\"580\"\/><\/figure><\/div>\n\n\n\n<p>Salientamos tamb\u00e9m o facto de estas frutas ajudarem na preven\u00e7\u00e3o de doen\u00e7as card\u00edacas e ajudarem na hidrata\u00e7\u00e3o do organismo devido ao facto de serem muito ricas em \u00e1gua. Devido a esta \u00faltima caracter\u00edstica tal ajuda na diminui\u00e7\u00e3o da pris\u00e3o de ventre devido \u00e0 riqueza destas frutas em fibras. Estes alimentos tamb\u00e9m s\u00e3o um grande aliado no que toca a combater a falta de ferro, pelo que se tem propens\u00e3o a anemia, uma fruta c\u00edtrica por dia ajuda-o a prevenir o problema.<\/p>\n\n\n\n<p>Sabia ainda que estas frutas podem ajud\u00e1-la a manter uma boa apar\u00eancia? Sim, as frutas c\u00edtricas ajudam a emagrecer pelas suas poucas calorias e ajudam a manter uma pele bonita e saud\u00e1vel. Isto devido \u00e0 sua composi\u00e7\u00e3o de antioxidantes que ajudam a prevenir os danos causados por radicais livres \u00e0s suas c\u00e9lulas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-3-1024x682.jpg\" alt=\"Vitamina C: Qual a import\u00e2ncia das Frutas C\u00edtricas?\" class=\"wp-image-2588\" width=\"582\" height=\"387\" srcset=\"https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-3-1024x682.jpg 1024w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-3-510x340.jpg 510w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-3-300x200.jpg 300w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-3-768x512.jpg 768w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-3-370x247.jpg 370w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-3-770x513.jpg 770w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-3.jpg 1280w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"has-text-align-center\"><strong>H\u00e1 alguma &#8220;\u00e9poca ideal&#8221; para consumo de frutas c\u00edtricas?<\/strong><\/h3>\n\n\n\n<p>N\u00e3o h\u00e1 uma \u201c\u00e9poca fixa\u201d para se consumirem as frutas c\u00edtricas. Ali\u00e1s as mesmas s\u00e3o altamente recomendadas na gravidez e na amamenta\u00e7\u00e3o. S\u00e3o uma grande ajuda para a mulher no que toca a ajudar a mulher a ingerir a quantidade de vitamina C de que necessita para o seu organismo. Naturalmente devem ser consumidas com um certo cuidado pois a mulher tende a ter essa vitamina mais elevada quer durante a gravidez quer durante a lacta\u00e7\u00e3o.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-1-1024x667.jpg\" alt=\"Vitamina C: Qual a import\u00e2ncia das Frutas C\u00edtricas?\" class=\"wp-image-2586\" width=\"587\" height=\"382\" srcset=\"https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-1-1024x667.jpg 1024w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-1-510x332.jpg 510w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-1-300x195.jpg 300w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-1-768x500.jpg 768w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-1-370x241.jpg 370w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-1-770x502.jpg 770w, https:\/\/dev.wisdomignite.pt\/cea\/wp-content\/uploads\/2021\/05\/VitaminaC-1.jpg 1280w\" sizes=\"(max-width: 587px) 100vw, 587px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"has-text-align-center\">Qual \u00e9 a defini\u00e7\u00e3o &#8220;geral&#8221; das frutas c\u00edtricas?<\/h3>\n\n\n\n<p>De uma forma geral, as frutas c\u00edtricas s\u00e3o definidas como todas aquelas que t\u00eam uma elevada quantidade de \u00e1cido asc\u00f3rbico (mais especificamente vitamina C) que \u00e9 respons\u00e1vel pelo sabor \u00e1cido e adocicado dessas frutas. Entre os principais exemplos de frutas c\u00edtricas podemos destacar os seguintes exemplos:<\/p>\n\n\n\n<ul><li>Laranja,<\/li><li>Tangerina,<\/li><li>Lim\u00e3o,<\/li><li>Lima,<\/li><li>Morango,<\/li><li>Kiwi.<\/li><\/ul>\n\n\n\n<h3 class=\"has-text-align-center\">Qual a melhor forma de consumir frutas c\u00edtricas?<\/h3>\n\n\n\n<p>A melhor forma de consumir estes frutos \u00e9 ao natural, sem qualquer forma de processamento, visto que os alimentos com vitamina C tendem a estragar-se com luz, ar e calor. Se tem sumos feitos de frutas c\u00edtricas, deve sim coloca-los na geleira preferencialmente numa jarra escura e tapada de modo a evitar que se estraguem.<\/p>\n\n\n\n<p>Mas ser\u00e1 que bolos e outras coinfec\u00e7\u00f5es que envolvam frutas c\u00edtricas t\u00eam na mesma a vitamina C presente? A resposta a essa quest\u00e3o, caso a coinfec\u00e7\u00e3o tenha ido ao forno, \u00e9 n\u00e3o. Isto porque ao ir ao forno o calor intenso destr\u00f3i a vitamina.<\/p>\n\n\n\n<h4 class=\"has-text-align-center\">Quais destes alimentos n\u00e3o faltam na sua alimenta\u00e7\u00e3o? Diga-nos quais nos coment\u00e1rios.&nbsp;<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Muitos falam acerca da import\u00e2ncia que as frutas c\u00edtricas t\u00eam para com o sistema imunol\u00f3gico. Nesta categoria podemos incluir frutos como a laranja, a tangerina, o abacaxi e o lim\u00e3o. Numa era marcada pela COVID-19 que g\u00e9nero de import\u00e2ncia acabam por ter estas frutas? A Coutinho &amp; Arezes hoje explica-lhe. Qual a import\u00e2ncia das Frutas [&#8230;]\n","protected":false},"author":4,"featured_media":2586,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[262,261],"tags":[],"_links":{"self":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/posts\/2584"}],"collection":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/comments?post=2584"}],"version-history":[{"count":4,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/posts\/2584\/revisions"}],"predecessor-version":[{"id":2674,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/posts\/2584\/revisions\/2674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/media\/2586"}],"wp:attachment":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/media?parent=2584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/categories?post=2584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/tags?post=2584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}