{"id":2545,"date":"2021-05-10T08:41:47","date_gmt":"2021-05-10T08:41:47","guid":{"rendered":"https:\/\/dev.wisdomignite.pt\/cea\/?page_id=2545"},"modified":"2021-06-30T10:53:43","modified_gmt":"2021-06-30T09:53:43","slug":"termos-e-condicoes","status":"publish","type":"page","link":"https:\/\/dev.wisdomignite.pt\/cea\/termos-e-condicoes\/","title":{"rendered":"Termos e Condi\u00e7\u00f5es"},"content":{"rendered":"\n<h2 class=\"has-text-align-center\"><strong>CONDI\u00c7\u00d5ES GERAIS DE CONTRATA\u00c7\u00c3O E UTILIZA\u00c7\u00c3O<\/strong><\/h2>\n\n\n\n<ul><li>Titularidade do dom\u00ednio&nbsp;www.coutinhoearezes.pt<\/li><li>Pol\u00edtica de Privacidade<\/li><li>Pol\u00edtica de Cookies<\/li><li>Lit\u00edgios de Consumo<\/li><\/ul>\n\n\n\n<p>Para qualquer esclarecimento relacionado com o s\u00edtio&nbsp;www.coutinhoearezes.pt&nbsp;ou com as presentes Condi\u00e7\u00f5es Gerais de Contrata\u00e7\u00e3o e Utiliza\u00e7\u00e3o (CGCU) poder\u00e1 contactar o Servi\u00e7o de Apoio ao Cliente do www.coutinhoearezes.pt atrav\u00e9s de qualquer um dos seguintes meios:<\/p>\n\n\n\n<ul><li>Email: geral@coutinhoearezes.pt<\/li><li>Telefone: 253 813 151<\/li><\/ul>\n\n\n\n<ol type=\"1\"><li><strong>TITULARIDADE DO DOM\u00cdNIO&nbsp;www.coutinhoearezes.pt<\/strong><\/li><\/ol>\n\n\n\n<p>O site&nbsp;www.coutinhoearezes.pt&nbsp;encontra-se registado ao abrigo do \u201cRegulamento do registo de dom\u00ednios\/subdom\u00ednios de .PT\u201d, e \u00e9 propriedade da empresa&nbsp;<strong>Coutinho &amp; Arezes &#8211; Com\u00e9rcio de Batata, Fruta e Hort\u00edcolas Lda&nbsp;<\/strong>com o NIF 506686140,&nbsp;entidade respons\u00e1vel pelo&nbsp;<em>www.coutinhoearezes.pt.<\/em><\/p>\n\n\n\n<p>Para qualquer esclarecimento relacionado com o s\u00edtio&nbsp;www.coutinhoearezes.pt&nbsp;ou com as presentes Condi\u00e7\u00f5es Gerais de Contrata\u00e7\u00e3o e Utiliza\u00e7\u00e3o (CGCU) poder\u00e1 contactar o Servi\u00e7o de Apoio ao Cliente da www.coutinhoearezes.pt atrav\u00e9s de qualquer um dos seguintes meios:<\/p>\n\n\n\n<ul><li>Email: geral@coutinhoearezes.pt<\/li><li>Telefone: 253 813 151<\/li><\/ul>\n\n\n\n<ol type=\"1\" start=\"2\"><li>POL\u00cdTICA DE PRIVACIDADE<\/li><\/ol>\n\n\n\n<p>A empresa&nbsp;<strong>Coutinho &amp; Arezes &#8211; Com\u00e9rcio de Batata, Fruta e Hort\u00edcolas Lda&nbsp;<\/strong>(doravante denominado \u201cwww.coutinhoearezes.pt\u201d)&nbsp;entidade respons\u00e1vel pelo site&nbsp;<em>www.coutinhoearezes.pt<\/em>&nbsp;valoriza a privacidade dos seus membros e neste sentido compromete-se a respeit\u00e1-la, garantindo o sigilo e prote\u00e7\u00e3o dos dados registados pelos utilizadores.<\/p>\n\n\n\n<p>A presente Declara\u00e7\u00e3o de Privacidade, tem como intuito assegurar aos utilizadores condi\u00e7\u00f5es de Seguran\u00e7a e de Privacidade, sendo apenas solicitados e recolhidos os dados necess\u00e1rios \u00e0 presta\u00e7\u00e3o do servi\u00e7o, de acordo com as indica\u00e7\u00f5es expl\u00edcitas no site. O utilizador tem plena liberdade para aceder aos seus dados, retific\u00e1-los ou elimin\u00e1-los.<\/p>\n\n\n\n<p><strong>2.1. IDENTIFICA\u00c7\u00c3O DO RESPONS\u00c1VEL PELO TRATAMENTO<\/strong><\/p>\n\n\n\n<ul><li><strong>Empresa: <\/strong>Coutinho &amp; Arezes &#8211; Com\u00e9rcio de Batata, Fruta e Hort\u00edcolas Lda<\/li><li><strong>NIF: <\/strong>506686140<\/li><li><strong>Contacto Encarregado da Prote\u00e7\u00e3o de Dados: <\/strong>geral@coutinhoearezes.pt<\/li><\/ul>\n\n\n\n<p><strong>2.2. INFORMA\u00c7\u00c3O E CONSENTIMENTO<\/strong><\/p>\n\n\n\n<p>A Lei da Prote\u00e7\u00e3o de Dados Pessoais (em diante \u201cLPDP\u201d) e o Regulamento Geral de Prote\u00e7\u00e3o de Dados (Regulamento (UE) 2016\/679 do Parlamento Europeu e do Conselho de 27 de abril de 2016, em diante \u201cRGPD\u201d) asseguram a prote\u00e7\u00e3o das pessoas singulares no que diz respeito ao tratamento de dados pessoais e \u00e0 livre circula\u00e7\u00e3o desses dados.<\/p>\n\n\n\n<p>Nos termos legais s\u00e3o considerados \u201cdados pessoais\u201d qualquer informa\u00e7\u00e3o, de qualquer natureza e independentemente do respetivo suporte, incluindo som e imagem, relativa a uma pessoa singular identificada ou identific\u00e1vel, pelo que a prote\u00e7\u00e3o n\u00e3o abrange os dados de pessoas coletivas.<\/p>\n\n\n\n<p>Mediante a aceita\u00e7\u00e3o da presente Pol\u00edtica de Privacidade o utilizador presta o seu consentimento informado, expresso, livre e inequ\u00edvoco para que os dados pessoais fornecidos atrav\u00e9s do site&nbsp;www.coutinhoearezes.pt sejam inclu\u00eddos num ficheiro da responsabilidade do www.coutinhoearezes.pt, cujo tratamento nos termos da LPDP e do RGPD cumpre as medidas de seguran\u00e7a t\u00e9cnicas e organizativas adequadas.<\/p>\n\n\n\n<p>O www.coutinhoearezes.pt, mant\u00e9m uma base de dados com o registo dos seus clientes. Os dados presentes nesta base s\u00e3o unicamente os dados prestados pelos pr\u00f3prios na altura do seu registo, sendo recolhidos e processados automaticamente, nos termos aprovados pela Comiss\u00e3o Nacional de Prote\u00e7\u00e3o de Dados, pelo www.coutinhoearezes.pt, entidade respons\u00e1vel pelo correspondente ficheiro.<\/p>\n\n\n\n<p>Em caso algum ser\u00e1 solicitada informa\u00e7\u00e3o sobre convic\u00e7\u00f5es filos\u00f3ficas ou pol\u00edticas, filia\u00e7\u00e3o partid\u00e1ria ou sindical, f\u00e9 religiosa, vida privada e origem racial ou \u00e9tnica bem como os dados relativos \u00e0 sa\u00fade e \u00e0 vida sexual, incluindo os dados gen\u00e9ticos.<\/p>\n\n\n\n<p>Em caso algum levaremos a cabo qualquer das seguintes atividades com os dados pessoais que nos sejam facultados atrav\u00e9s deste site:<\/p>\n\n\n\n<ul><li>Ceder a outras pessoas ou outras entidades, sem o consentimento pr\u00e9vio do titular dos dados;<\/li><\/ul>\n\n\n\n<p><strong>2.3. FINALIDADES DO TRATAMENTO DE DADOS PESSOAIS<\/strong><\/p>\n\n\n\n<p>Os dados pessoais que tratamos atrav\u00e9s desta p\u00e1gina ser\u00e3o unicamente utilizados para as seguintes finalidades:<\/p>\n\n\n\n<ul><li>(i) Processamento de encomendas;<\/li><li>(ii) Comunica\u00e7\u00e3o com clientes e esclarecimento de d\u00favidas;<\/li><li>(iii) Processamento de pedidos de informa\u00e7\u00e3o;<\/li><li>(iv) Processamento de reclama\u00e7\u00f5es;<\/li><li>(v) Atividades de an\u00e1lise estat\u00edstica;<\/li><li>(vi) Verificar, manter e desenvolver sistemas e an\u00e1lises estat\u00edsticas;<\/li><li>(vii) Comunica\u00e7\u00f5es de marketing direto (caso tenha consentido no tratamento dos seus dados pessoais para esta finalidade);<\/li><li>(viii) Preven\u00e7\u00e3o e combate \u00e0 fraude;<\/li><li>(ix) Solicita\u00e7\u00e3o de coment\u00e1rios a produtos ou servi\u00e7os adquiridos;<\/li><li>(x) Realiza\u00e7\u00e3o de inqu\u00e9ritos de satisfa\u00e7\u00e3o.<\/li><\/ul>\n\n\n\n<p>O www.coutinhoearezes.pt garante a confidencialidade de todos os dados fornecidos pelos seus clientes. N\u00e3o obstante o&nbsp;www.coutinhoearezes.pt procede \u00e0 recolha e ao tratamento de dados de forma segura e que impede a sua perda ou manipula\u00e7\u00e3o, utilizando as t\u00e9cnicas mais aperfei\u00e7oadas para o efeito, informamos que a recolha em rede aberta permite a circula\u00e7\u00e3o dos dados pessoais sem condi\u00e7\u00f5es de seguran\u00e7a, correndo o risco de ser vistos e utilizados por terceiros n\u00e3o autorizados.<\/p>\n\n\n\n<p>O Website do&nbsp;<em>www.coutinhoearezes.pt<\/em>&nbsp;disp\u00f5e de um&nbsp;<em>chat<\/em>, no qual os utilizadores podem colocar quest\u00f5es e assim retirar um melhor aproveitamento de toda a oferta www.coutinhoearezes.pt. Se os utilizadores fornecerem dados pessoais ao&nbsp;www.coutinhoearezes.pt atrav\u00e9s do referido&nbsp;<em>chat<\/em>, os mesmos n\u00e3o ser\u00e3o utilizados para qualquer finalidade distinta daquilo que for solicitado pelo utilizador.<\/p>\n\n\n\n<p>Por outro lado, o utilizador consente que se possa aceder \u00e0 informa\u00e7\u00e3o relativa ao servi\u00e7o contratado com o www.coutinhoearezes.pt com o fim de lhe poder oferecer servi\u00e7os adicionais ao contratado.<\/p>\n\n\n\n<p>No momento da recolha dos dados pessoais, salvo nos campos em que for indicado o contr\u00e1rio, o utilizador poder\u00e1, voluntariamente, disponibilizar os dados pessoais, sem que a falta de resposta implique um decr\u00e9scimo na qualidade ou quantidade dos servi\u00e7os correspondentes (a menos que esteja indicada outra coisa). N\u00e3o obstante, a falta de resposta aos dados, considerados obrigat\u00f3rios, implicar\u00e1 a impossibilidade de aceder ao servi\u00e7o para o qual os dados foram solicitados.<\/p>\n\n\n\n<p>Caso n\u00e3o concorde com as condi\u00e7\u00f5es acima referidas, o&nbsp;www.coutinhoearezes.pt n\u00e3o poder\u00e1 contratar com o utilizador atrav\u00e9s da sua p\u00e1gina Web.<\/p>\n\n\n\n<p><strong>2.4. CESS\u00c3O DE DADOS PESSOAIS<\/strong><\/p>\n\n\n\n<p>Por forma a poder cumprir com o objeto do presente website, o&nbsp;www.coutinhoearezes.pt ir\u00e1 ceder os seus dados pessoais a outras entidades, que os ir\u00e3o tratar, para as seguintes finalidades:<\/p>\n\n\n\n<ul><li>Atividades de gest\u00e3o e processamento de pagamentos;<\/li><li>Atividades de processamento e envio de encomendas;<\/li><li>Presta\u00e7\u00e3o dos servi\u00e7os contratados.<\/li><\/ul>\n\n\n\n<p>As entidades a quem o&nbsp;www.coutinhoearezes.pt ir\u00e1 ceder os seus dados pessoais para os tratarem nos termos acima referidos ter\u00e3o a seguinte natureza:<\/p>\n\n\n\n<ul><li>Entidades seguradoras;<\/li><li>Entidades de gest\u00e3o e processamento de pagamentos;<\/li><li>Entidades de processamento e envio de encomendas;<\/li><li>Entidades terceiras relacionadas com a presta\u00e7\u00e3o dos servi\u00e7os contratados.<\/li><\/ul>\n\n\n\n<p><strong>2.5. ARMAZENAMENTO DOS SEUS DADOS PESSOAIS<\/strong><\/p>\n\n\n\n<p>Os dados recolhidos pelo www.coutinhoearezes.pt podem ser transferidos e armazenados num destino fora do Espa\u00e7o Econ\u00f3mico Europeu (\u201cEEE\u201d). Ao submeter os seus dados pessoais, est\u00e1 a concordar com esta transfer\u00eancia, armazenamento ou processamento.<\/p>\n\n\n\n<p>Todas as informa\u00e7\u00f5es fornecidas ao www.coutinhoearezes.pt, s\u00e3o armazenadas em seguran\u00e7a, nos nossos servidores, e\/ou servidores dos nossos fornecedores de servi\u00e7os, que podem estar localizados em pa\u00edses fora do Espa\u00e7o Econ\u00f3mico Europeu (\u201cEEE\u201d). Tomamos todas as medidas razoavelmente necess\u00e1rias para assegurar que os seus dados sejam tratados com seguran\u00e7a e de acordo com esta pol\u00edtica de privacidade.<\/p>\n\n\n\n<p><strong>2.6. MEDIDAS DE SEGURAN\u00c7A<\/strong><\/p>\n\n\n\n<p>O&nbsp;www.coutinhoearezes.pt declara que implementou e continuar\u00e1 a implementar as medidas de seguran\u00e7a de natureza t\u00e9cnica e organizativa necess\u00e1rias para garantir a seguran\u00e7a dos dados de car\u00e1cter pessoal que lhe sejam fornecidos visando evitar a sua altera\u00e7\u00e3o, perda, tratamento e\/ou acesso n\u00e3o autorizado, tendo em conta o estado atual da tecnologia, a natureza dos dados armazenados e os riscos a que est\u00e3o expostos.<\/p>\n\n\n\n<p>O www.coutinhoearezes.pt garante a confidencialidade de todos os dados fornecidos pelos seus clientes quer no registo, quer no processo de compra\/encomenda de produtos ou servi\u00e7os. A recolha e tratamento de dados realiza-se de forma segura e que impede a sua perda ou manipula\u00e7\u00e3o. Todos os dados ser\u00e3o inseridos num Servidor Seguro (SSL de 128 bits) que os encripta\/codifica (transforma num c\u00f3digo). O utilizador poder\u00e1 verificar que o seu browser \u00e9 seguro se o s\u00edmbolo do cadeado aparecer ou se o endere\u00e7o come\u00e7ar com https em vez de http.<\/p>\n\n\n\n<p>Os dados pessoais s\u00e3o tratados com o n\u00edvel de prote\u00e7\u00e3o legalmente exig\u00edvel para garantir a seguran\u00e7a dos mesmos e evitar a sua altera\u00e7\u00e3o, perda, tratamento ou acesso n\u00e3o autorizado, tendo em conta o estado da tecnologia, sendo o utilizador consciente e aceitando que as medidas de seguran\u00e7a em Internet n\u00e3o s\u00e3o inexpugn\u00e1veis.<\/p>\n\n\n\n<p>O www.coutinhoearezes.pt, sempre que aceda a qualquer dado pessoal, compromete-se a:<\/p>\n\n\n\n<ul><li>Armazen\u00e1-los por interm\u00e9dio de medidas de seguran\u00e7a, legalmente exig\u00edveis, de natureza t\u00e9cnica e organizacional, que garantam a sua seguran\u00e7a, evitando assim a altera\u00e7\u00e3o, perda, tratamento ou acesso n\u00e3o autorizado, em conformidade com o estado da tecnologia em cada momento, a natureza dos dados e os poss\u00edveis riscos a que estejam expostos;<\/li><li>Utilizar os dados exclusivamente para as finalidades previamente definidas;<\/li><li>Certificar-se de que os dados s\u00e3o tratados unicamente pelos trabalhadores cuja interven\u00e7\u00e3o seja necess\u00e1ria para a presta\u00e7\u00e3o do servi\u00e7o estando os mesmos obrigados ao dever de sigilo e confidencialidade. Existindo a possibilidade de a informa\u00e7\u00e3o ser revelada a terceiros, estes devem ser obrigados a guardar a devida confidencialidade em conformidade com o previsto neste documento.<\/li><\/ul>\n\n\n\n<p><strong>2.7. COMUNICA\u00c7\u00d5ES COMERCIAIS E PROMOCIONAIS<\/strong><\/p>\n\n\n\n<p>Um dos prop\u00f3sitos para os quais tratamos dados pessoais fornecidos pelos utilizadores \u00e9 enviar comunica\u00e7\u00f5es eletr\u00f3nicas com informa\u00e7\u00f5es relativas a comunica\u00e7\u00f5es comerciais e promocionais.<\/p>\n\n\n\n<p>Sempre que fizermos uma comunica\u00e7\u00e3o deste tipo, ser\u00e1 direcionado exclusivamente aos utilizadores que as tenham autorizado previamente e de forma expressa.<\/p>\n\n\n\n<p>De acordo com o disposto na Decreto-Lei n.\u00ba 7\/2004, de 7 de janeiro, no caso de o utilizador desejar deixar de receber comunica\u00e7\u00f5es comerciais ou promocionais do www.coutinhoearezes.pt, poder\u00e1 solicitar a oposi\u00e7\u00e3o do servi\u00e7o enviando um e-mail para:&nbsp;geral@coutinhoearezes.pt<\/p>\n\n\n\n<p><strong>2.8. EXERC\u00cdCIO DOS DIREITOS<\/strong><\/p>\n\n\n\n<p>De acordo com as disposi\u00e7\u00f5es da LDPD e do RGPD, o utilizador pode exercer a todo o tempo os seus direitos de acesso, retifica\u00e7\u00e3o, apagamento, limita\u00e7\u00e3o, oposi\u00e7\u00e3o e portabilidade, atrav\u00e9s de solicita\u00e7\u00e3o por qualquer dos seguintes meios:<\/p>\n\n\n\n<ul><li>E-mail:&nbsp;geral@coutinhoearezes.pt<\/li><\/ul>\n\n\n\n<p>Caso o utilizador deseje, a qualquer momento, deixar de fazer parte da base de dados www.coutinhoearezes.pt poder\u00e1 exercer esse direito atrav\u00e9s destes contactos.<\/p>\n\n\n\n<ol type=\"1\" start=\"3\"><li>POL\u00cdTICA DE COOKIES<\/li><\/ol>\n\n\n\n<p>Esta Pol\u00edtica de Cookies \u00e9 parte integrante da Pol\u00edtica de Privacidade de www.coutinhoearezes.pt (doravante denominado \u201cWebsite\u201d). O acesso e navega\u00e7\u00e3o no site, ou o uso dos seus servi\u00e7os, implica a aceita\u00e7\u00e3o dos termos e condi\u00e7\u00f5es contidos na Pol\u00edtica de Privacidade.<\/p>\n\n\n\n<p>Para facilitar e proporcionar uma melhor experi\u00eancia de navega\u00e7\u00e3o atrav\u00e9s do website, o www.coutinhoearezes.pt. (doravante, a \u201cwww.coutinhoearezes.pt\u201d), informa que utiliza Cookies ou outros arquivos de funcionalidade similar (a seguir \u201cCookies\u201d).<\/p>\n\n\n\n<p>Devido ao modo como funcionam os standards de comunica\u00e7\u00e3o de Internet, o acesso aos websites pode implicar a utiliza\u00e7\u00e3o de cookies. Em qualquer caso, informamos que a {nome} \u00e9 respons\u00e1vel pelos Cookies e pelo tratamento dos dados obtidos atrav\u00e9s dos cookies pr\u00f3prios e de terceiros, decidindo sobre o prop\u00f3sito, conte\u00fado e uso do tratamento das informa\u00e7\u00f5es recolhidas.<\/p>\n\n\n\n<p><strong>2.1. O que \u00e9 um Cookie?<\/strong><br>Os cookies s\u00e3o arquivos que cont\u00eam pequenas quantidades de informa\u00e7\u00f5es que s\u00e3o descarregadas para o dispositivo do utilizador quando visita uma p\u00e1gina da Web. O objetivo principal \u00e9 reconhecer o utilizador sempre que ele acede ao site, permitindo tamb\u00e9m melhorar a qualidade e oferecer um melhor uso do site. Resumidamente: visam simplificar a sua navega\u00e7\u00e3o em www.coutinhoearezes.pt<\/p>\n\n\n\n<p>Os cookies s\u00e3o essenciais para o funcionamento da Internet; estes n\u00e3o danificam o equipamento \/ dispositivo do utilizador e, se estiverem ativados na configura\u00e7\u00e3o do seu navegador, ajudam a identificar e resolver poss\u00edveis erros na opera\u00e7\u00e3o do site.<\/p>\n\n\n\n<p><strong>2.2. Uso de Cookies pelo www.coutinhoearezes.pt<\/strong><br>Ao aceder ao site, o utilizador aceita expressamente o uso deste tipo de Cookies nos seus dispositivos. Se desativar os Cookies, a sua navega\u00e7\u00e3o no site poder\u00e1 n\u00e3o ser otimizada e algumas das funcionalidades dispon\u00edveis no site podem n\u00e3o funcionar corretamente.<\/p>\n\n\n\n<p>Especificamente, o www.coutinhoearezes.pt usa Cookies para os prop\u00f3sitos estabelecidos abaixo. Se, no futuro, o www.coutinhoearezes.pt usar outros com a finalidade de conceder mais e melhores servi\u00e7os, o utilizador ser\u00e1 devidamente informado disso.<\/p>\n\n\n\n<p><strong>2.3. Cookies Utilizados<\/strong><br><strong>\u2013 Cookies de Prefer\u00eancias<\/strong><br>Estes cookies permitem que os Websites memorizem informa\u00e7\u00f5es que alteram o comportamento e o aspeto do Website. Estes cookies tamb\u00e9m o podem ajudar a alterar o tamanho do texto, o tipo de letra e outras partes personaliz\u00e1veis de p\u00e1ginas Web. A perda das informa\u00e7\u00f5es armazenadas num cookie de prefer\u00eancia pode tornar a experi\u00eancia do Website menos funcional, mas n\u00e3o dever\u00e1 impedir o seu funcionamento.<\/p>\n\n\n\n<p><strong>\u2013 Cookies de Seguran\u00e7a<\/strong><br>Os cookies de seguran\u00e7a s\u00e3o utilizados para autenticar utilizadores e evitar a utiliza\u00e7\u00e3o fraudulenta de credenciais de in\u00edcio de sess\u00e3o e proteger dados de pessoas n\u00e3o autorizadas. Por exemplo, permite bloquear muitos tipos de ataque, como tentativas de roubo do conte\u00fado de formul\u00e1rios que preenche em p\u00e1ginas Web.<\/p>\n\n\n\n<p><strong>\u2013 Cookies de Processos<\/strong><br>Os cookies de processo ajudam o Website a funcionar e a disponibilizar servi\u00e7os que o visitante do Website espera, como navegar em p\u00e1ginas Web ou aceder a \u00e1reas seguras do Website. Sem estes cookies, o Website n\u00e3o consegue funcionar corretamente.<\/p>\n\n\n\n<p><strong>\u2013 Cookies de Estado da Sess\u00e3o<\/strong><br>Os Websites recolhem muitas vezes informa\u00e7\u00f5es sobre a forma como os utilizadores interagem com uma determinada p\u00e1gina Web. Isso pode incluir as p\u00e1ginas que os utilizadores visitam com mais frequ\u00eancia e se os utilizadores recebem mensagens de erro de determinadas p\u00e1ginas. Os chamados \u201ccookies de estado da sess\u00e3o ajudam a melhorar os servi\u00e7os das empresas, de forma a melhorar a experi\u00eancia de navega\u00e7\u00e3o dos nossos utilizadores. Bloquear ou eliminar estes cookies n\u00e3o torna o Website inutiliz\u00e1vel.<\/p>\n\n\n\n<p><strong>\u2013 Cookies de An\u00e1lise<\/strong><br>Estes cookies ajudam os propriet\u00e1rios de Websites e de aplica\u00e7\u00f5es a entender o envolvimento dos seus visitantes com as suas p\u00e1ginas web. Estes podem utilizar um conjunto de cookies para recolher informa\u00e7\u00f5es e reportar estat\u00edsticas de utiliza\u00e7\u00e3o dos Websites sem identificar pessoalmente os visitantes individuais.<\/p>\n\n\n\n<p><strong>\u2013 Cookies de Publicidade<\/strong><br>Estes Cookies (por exemplo de plataformas como o Google ou o Facebook) ajudam o propriet\u00e1rio do website e \/ ou aplica\u00e7\u00f5es a fazer a capta\u00e7\u00e3o de&nbsp;<em>\u201cLeads\u201d<\/em>&nbsp;para a angaria\u00e7\u00e3o de novos assessores\/clientes\/utilizadores do Website. Os dados Recolhidos s\u00e3o an\u00f3nimos e n\u00e3o \u00e9 poss\u00edvel identificar o utilizador. S\u00e3o usados para limitar o n\u00famero de vezes que um an\u00fancio \u00e9 visualizado e ajudam a medir a efic\u00e1cia de uma campanha publicit\u00e1ria.<\/p>\n\n\n\n<p><strong>\u2013 Cookies e plug-ins de redes sociais (bot\u00f5es sociais)<\/strong><br>Estes cookies sociais destinam-se a permitir que os utilizadores partilhem p\u00e1ginas e conte\u00fados atrav\u00e9s de redes sociais de terceiros. Permitem tamb\u00e9m segmentar a oferta de publicidade nas redes sociais.<\/p>\n\n\n\n<p>O nosso site tamb\u00e9m usa plug-ins ou bot\u00f5es sociais.<\/p>\n\n\n\n<p>Os plug-ins sociais tornam poss\u00edvel facilitar a partilha de p\u00e1ginas e conte\u00fados do site www.coutinhoearezes.pt nas diversas plataformas sociais. Por exemplo, permitem ao utilizador gostar (\u201clike\u201d) e partilhar informa\u00e7\u00f5es do nosso site com os seus amigos nas redes sociais.<\/p>\n\n\n\n<p>Para isso, os plug-ins usam cookies para rastrear a navega\u00e7\u00e3o dos utilizadores, sejam utilizadores dessas plataformas ou n\u00e3o, e para verificar se est\u00e3o ou n\u00e3o ligados \u00e0 rede social durante a navega\u00e7\u00e3o. Estes cookies tamb\u00e9m permitem segmentar as ofertas de publicidade nessas plataformas.<\/p>\n\n\n\n<p>Para obter mais informa\u00e7\u00f5es sobre o uso de dados pessoais em rela\u00e7\u00e3o \u00e0s redes sociais, podem ser consultadas as pol\u00edticas de privacidade das redes sociais de terceiros em quest\u00e3o.<\/p>\n\n\n\n<p>Todas as cookies s\u00e3o mantidas apenas pelo tempo estritamente necess\u00e1rio \u00e0 sua utiliza\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>3.4. Configura\u00e7\u00e3o do utilizador para evitar cookies<\/strong><br>Em conformidade com a legisla\u00e7\u00e3o vigente, fornecemos as informa\u00e7\u00f5es que permitem ao utilizador configurar o seu browser para gerir e manter a sua privacidade e seguran\u00e7a em rela\u00e7\u00e3o aos Cookies. Portanto, fornecemos informa\u00e7\u00f5es e links para os sites de suporte oficiais dos navegadores principais para que o utilizador possa decidir se aceita ou n\u00e3o o uso de Cookies.<\/p>\n\n\n\n<p>As defini\u00e7\u00f5es de cookies podem ser alteradas nas prefer\u00eancias do browser, seguindo as indica\u00e7\u00f5es constantes nos links:<br><a href=\"https:\/\/support.google.com\/chrome\/answer\/95647\" target=\"_blank\" rel=\"noopener\">Chrome<\/a><br><a href=\"https:\/\/support.mozilla.org\/pt-PT\/kb\/ativar-e-desativar-cookies-que-os-websites-utiliza\" target=\"_blank\" rel=\"noopener\">Firefox<\/a><br><a href=\"https:\/\/support.microsoft.com\/pt-pt\/help\/17442\/windows-internet-explorer-delete-manage-cookies\" target=\"_blank\" rel=\"noopener\">Internet Explorer<\/a><br><a href=\"https:\/\/support.apple.com\/kb\/ph21411?locale=pt_PT\" target=\"_blank\" rel=\"noopener\">Safari<\/a><\/p>\n\n\n\n<p>Para obter mais informa\u00e7\u00f5es sobre cookies, incluindo para saber que cookies foram instalados e como podem ser geridos e eliminados, o utilizador pode aceder a www.allaboutcookies.org. Se o utilizador n\u00e3o quiser que as suas visitas a sites Web sejam detetadas pelo Google Analytics, dever\u00e1 aceder a http:\/\/tools.google.com\/dlpage\/gaoptout.<\/p>\n\n\n\n<p>Deve entender-se que o utilizador aceita o uso de cookies se continuar a navegar nesta p\u00e1gina sem antes proceder \u00e0 sua desativa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Lit\u00edgios de Consumo<\/p>\n\n\n\n<ol type=\"1\" start=\"4\"><li>LIT\u00cdGIOS DE CONSUMO<\/li><\/ol>\n\n\n\n<p>Em caso de lit\u00edgio de consumo, o consumidor pode recorrer \u00e0 Plataforma Europeia de Resolu\u00e7\u00e3o de Lit\u00edgios em Linha, dispon\u00edvel em&nbsp;<a href=\"http:\/\/ec.europa.eu\/consumers\/odr\" target=\"_blank\" rel=\"noopener\">http:\/\/ec.europa.eu\/consumers\/odr<\/a>&nbsp;ou \u00e0s seguintes entidades de resolu\u00e7\u00e3o alternativa de lit\u00edgios de consumo:<\/p>\n\n\n\n<p><strong>4.1. CNIACC \u2013 Centro Nacional de Informa\u00e7\u00e3o e Arbitragem de Conflitos de Consumo<\/strong><br>Tel.: 213 847 484;<br>E-mail: cniacc@unl.pt;<br>Web: www.arbitragemdeconsumo.org \/ www.facebook.com\/cniacc<\/p>\n\n\n\n<p><strong>4.2. CIMAAL \u2013 Centro de Informa\u00e7\u00e3o, Media\u00e7\u00e3o e Arbitragem de Conflitos de Consumo do Algarve<\/strong><br>Tel.: 289 823 135;<br>E-mail: cimaal@mail.telepac.pt;<br>Web: www.consumidoronline.pt<\/p>\n\n\n\n<p><strong>4.3. Centro de Arbitragem de Conflitos de Consumo do Distrito de Coimbra<\/strong><br>Tel.: 239 821 690\/289;<br>E-mail: geral@centrodearbitragemdecoimbra.com;<br>Web: www.centrodearbitragemdecoimbra.com<\/p>\n\n\n\n<p><strong>4.4. Centro de Arbitragem de Conflitos de Consumo de Lisboa<\/strong><br>Tel.: 218 807 000 \/ 218807030;<br>E-mail: juridico@centroarbitragemlisboa.pt; director@centroarbitragemlisboa.pt;<br>Web: www.centroarbitragemlisboa.pt<\/p>\n\n\n\n<p><strong>4.5. Centro de Informa\u00e7\u00e3o de Consumo e Arbitragem do Porto<\/strong><br>Tel.: 225 508 349 \/ 225 029 791;<br>E-mail: cicap@mail.telepac.pt;<br>Web: www.cicap.pt<\/p>\n\n\n\n<p><strong>4.6. Centro de Arbitragem de Conflitos de Consumo do Vale do Ave\/Tribunal Arbitral<\/strong><br>Tel.: 253 422 410;<br>E-mail: triave@gmail.com;<br>Web: www.triave.pt<\/p>\n\n\n\n<p><strong>4.7. Centro de Informa\u00e7\u00e3o, Media\u00e7\u00e3o e Arbitragem de Consumo (Tribunal Arbitral de Consumo)<\/strong><br>Tel.: 253 617 604;<br>E-mail: geral@ciab.pt;<br>Web: www.ciab.pt<\/p>\n\n\n\n<p><strong>4.8. Centro de Arbitragem de Conflitos de Consumo da Regi\u00e3o Aut\u00f3noma da Madeira<\/strong><br>Morada: Rua Direita, 27 \u2013 1o Andar, 9050-405 Funchal;<br>Tel.: 291 215 070<br>E-mail: centroarbitragem.srias@madeira.gov.pt;<br>Web: www.srrh.gov-madeira.pt<\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es consulte o Portal do Consumidor em&nbsp;<a href=\"http:\/\/www.consumidor.pt\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.consumidor.pt<\/a><\/p>\n\n\n\n<p><strong>\u00daltima Atualiza\u00e7\u00e3o:<\/strong>&nbsp;10 de maio 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CONDI\u00c7\u00d5ES GERAIS DE CONTRATA\u00c7\u00c3O E UTILIZA\u00c7\u00c3O Titularidade do dom\u00ednio&nbsp;www.coutinhoearezes.pt Pol\u00edtica de Privacidade Pol\u00edtica de Cookies Lit\u00edgios de Consumo Para qualquer esclarecimento relacionado com o s\u00edtio&nbsp;www.coutinhoearezes.pt&nbsp;ou com as presentes Condi\u00e7\u00f5es Gerais de Contrata\u00e7\u00e3o e Utiliza\u00e7\u00e3o (CGCU) poder\u00e1 contactar o Servi\u00e7o de Apoio ao Cliente do www.coutinhoearezes.pt atrav\u00e9s de qualquer um dos seguintes meios: Email: geral@coutinhoearezes.pt Telefone: [&#8230;]\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"_links":{"self":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/pages\/2545"}],"collection":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/comments?post=2545"}],"version-history":[{"count":2,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/pages\/2545\/revisions"}],"predecessor-version":[{"id":2671,"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/pages\/2545\/revisions\/2671"}],"wp:attachment":[{"href":"https:\/\/dev.wisdomignite.pt\/cea\/wp-json\/wp\/v2\/media?parent=2545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}